{"id":1471,"date":"2017-03-02T12:52:23","date_gmt":"2017-03-02T12:52:23","guid":{"rendered":"http:\/\/fozsports-events.com\/?page_id=1471\/"},"modified":"2025-10-02T11:03:47","modified_gmt":"2025-10-02T11:03:47","slug":"team","status":"publish","type":"page","link":"https:\/\/fozsports-events.com\/en\/team\/","title":{"rendered":"Team"},"content":{"rendered":"<div id='av_section_1'  class='avia-section main_color avia-section-large avia-no-border-styling  avia-bg-style-scroll  avia-builder-el-0  el_before_av_layout_row  avia-builder-el-first   container_wrap sidebar_right' style=' '  ><div class='container' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-1471'><div class='entry-content-wrapper clearfix'>\n<div  style='padding-bottom:30px; font-size:70px;' class='av-special-heading av-special-heading-h1  blockquote modern-quote  avia-builder-el-1  el_before_av_one_full  avia-builder-el-first  av-thin-font av-inherit-size '><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >Team<strong>.<\/strong><\/h1><div class='special-heading-border'><div class='special-heading-inner-border' ><\/div><\/div><\/div>\n<div class=\"flex_column av_one_full  flex_column_div av-zero-column-padding first  avia-builder-el-2  el_after_av_heading  avia-builder-el-last  \" style='border-radius:0px; '><section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock  '   itemprop=\"text\" ><p style=\"text-align: center;\">Foz Sports &amp; Events was founded by Carles Foz, father and son, in 2010 with the goal of helping young prospects to develop their basketball careers.<\/p>\n<p style=\"text-align: center;\">Our team of professionals is ready to take our players careers to a new level anywhere of the World. <strong>Join us<\/strong>!<\/p>\n<\/div><\/section><\/div>\n\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div><div id='av-layout-grid-1'  class='av-layout-grid-container entry-content-wrapper alternate_color av-flex-cells     avia-builder-el-4  el_after_av_section  el_before_av_layout_row  submenu-not-first container_wrap sidebar_right' style=' '  >\n<div class=\"flex_cell no_margin av_one_third  avia-builder-el-5  el_before_av_cell_one_third  avia-builder-el-first   avia-full-stretch \"  style='background:url(https:\/\/fozsports-events.com\/wp-content\/uploads\/2025\/10\/Copia-de-10-1-1030x1030.png) top left no-repeat scroll; vertical-align:middle; padding:180px 60px 180px 60px ; ' ><div class='flex_cell_inner' ><\/div><\/div><div class=\"flex_cell no_margin av_one_third  avia-builder-el-6  el_after_av_cell_one_third  el_before_av_cell_one_third   \"  style='vertical-align:middle; padding:60px; ' ><div class='flex_cell_inner' ><p><div  style='padding-bottom:10px; font-size:30px;' class='av-special-heading av-special-heading-h3  blockquote modern-quote  avia-builder-el-7  el_before_av_iconlist  avia-builder-el-first  av-inherit-size '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Carles Foz Vidal<\/h3><div class ='av-subheading av-subheading_below  ' style='font-size:15px;'><p>Founder &amp; FIBA Agent<\/p>\n<\/div><div class='special-heading-border'><div class='special-heading-inner-border' ><\/div><\/div><\/div><br \/>\n<div  class='avia-icon-list-container   avia-builder-el-8  el_after_av_heading  avia-builder-el-last '><ul class='avia-icon-list avia-icon-list-left av-iconlist-small avia_animate_when_almost_visible avia-iconlist-animate'>\n<li><div  style='color:#d63e2d; ' class='iconlist_icon  avia-font-entypo-fontello'><span class='iconlist-char ' aria-hidden='true' data-av_icon='\ue8b1' data-av_iconfont='entypo-fontello'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='iconlist_content_wrap'><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small   '  itemprop=\"headline\"  >Spain | USA<\/div><\/header><div class='iconlist_content  '  itemprop=\"text\"  ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class='iconlist-timeline'><\/div><\/li>\n<li><div  style='color:#d63e2d; ' class='iconlist_icon  avia-font-fontawesome'><span class='iconlist-char ' aria-hidden='true' data-av_icon='\uf27e' data-av_iconfont='fontawesome'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='iconlist_content_wrap'><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small   '  itemprop=\"headline\"  >General Manager &amp; Basketball Agent<\/div><\/header><div class='iconlist_content  '  itemprop=\"text\"  ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class='iconlist-timeline'><\/div><\/li>\n<li><div  style='color:#d63e2d; ' class='iconlist_icon  avia-font-fontawesome'><span class='iconlist-char ' aria-hidden='true' data-av_icon='\uf19d' data-av_iconfont='fontawesome'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='iconlist_content_wrap'><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small   '  itemprop=\"headline\"  >Law Degree | Master in Sports Law | Master in Law Practice | Master in Coaching and Psychology of Sports High Performance<\/div><\/header><div class='iconlist_content  '  itemprop=\"text\"  ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class='iconlist-timeline'><\/div><\/li>\n<li><div  style='color:#d63e2d; ' class='iconlist_icon  avia-font-fontawesome'><span class='iconlist-char ' aria-hidden='true' data-av_icon='\uf1ab' data-av_iconfont='fontawesome'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='iconlist_content_wrap'><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small   '  itemprop=\"headline\"  >Spanish | Catalan | English<\/div><\/header><div class='iconlist_content  '  itemprop=\"text\"  ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class='iconlist-timeline'><\/div><\/li>\n<\/ul><\/div><\/p>\n<\/div><\/div><div class=\"flex_cell no_margin av_one_third  avia-builder-el-9  el_after_av_cell_one_third  avia-builder-el-last   \"  style='vertical-align:middle; padding:60px; background-color:#292929; ' ><div class='flex_cell_inner' ><section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock  '   itemprop=\"text\" ><p>Carles Foz Vidal, Lawyer, Master and University teacher in Sports Law.<br \/>\nHe founded the Agency in 2010 scouting and representing players since he was 18 years old.<br \/>\nHe is the current General Manager for FSE.<\/p>\n<\/div><\/section>\n<\/div><\/div><\/div><div id='av-layout-grid-2'  class='av-layout-grid-container entry-content-wrapper main_color av-flex-cells     avia-builder-el-11  el_after_av_layout_row  el_before_av_layout_row  submenu-not-first container_wrap sidebar_right' style=' '  >\n<div class=\"flex_cell no_margin av_one_third  avia-builder-el-12  el_before_av_cell_one_third  avia-builder-el-first   avia-full-stretch \"  style='background:url(https:\/\/fozsports-events.com\/wp-content\/uploads\/2025\/10\/Copia-de-10-2-1030x1030.png) top left no-repeat scroll; vertical-align:middle; padding:180px 60px 180px 60px ; ' ><div class='flex_cell_inner' ><\/div><\/div><div class=\"flex_cell no_margin av_one_third  avia-builder-el-13  el_after_av_cell_one_third  el_before_av_cell_one_third   \"  style='vertical-align:middle; padding:60px; ' ><div class='flex_cell_inner' ><p><div  style='padding-bottom:10px; font-size:30px;' class='av-special-heading av-special-heading-h3  blockquote modern-quote  avia-builder-el-14  el_before_av_iconlist  avia-builder-el-first  av-inherit-size '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Carles Foz Moreno<\/h3><div class ='av-subheading av-subheading_below  ' style='font-size:15px;'><p>Founder &amp; FIBA Agent<\/p>\n<\/div><div class='special-heading-border'><div class='special-heading-inner-border' ><\/div><\/div><\/div><br \/>\n<div  class='avia-icon-list-container   avia-builder-el-15  el_after_av_heading  avia-builder-el-last '><ul class='avia-icon-list avia-icon-list-left av-iconlist-small avia_animate_when_almost_visible avia-iconlist-animate'>\n<li><div  style='color:#d63e2d; ' class='iconlist_icon  avia-font-entypo-fontello'><span class='iconlist-char ' aria-hidden='true' data-av_icon='\ue8b1' data-av_iconfont='entypo-fontello'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='iconlist_content_wrap'><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small   '  itemprop=\"headline\"  >Spain<\/div><\/header><div class='iconlist_content  '  itemprop=\"text\"  ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class='iconlist-timeline'><\/div><\/li>\n<li><div  style='color:#d63e2d; ' class='iconlist_icon  avia-font-fontawesome'><span class='iconlist-char ' aria-hidden='true' data-av_icon='\uf27e' data-av_iconfont='fontawesome'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='iconlist_content_wrap'><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small   '  itemprop=\"headline\"  >FIBA Agent &amp; Legal Advisor<\/div><\/header><div class='iconlist_content  '  itemprop=\"text\"  ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class='iconlist-timeline'><\/div><\/li>\n<li><div  style='color:#d63e2d; ' class='iconlist_icon  avia-font-fontawesome'><span class='iconlist-char ' aria-hidden='true' data-av_icon='\uf19d' data-av_iconfont='fontawesome'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='iconlist_content_wrap'><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small   '  itemprop=\"headline\"  >Licensed in Law | Master and PhD in Sports Law<\/div><\/header><div class='iconlist_content  '  itemprop=\"text\"  ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class='iconlist-timeline'><\/div><\/li>\n<li><div  style='color:#d63e2d; ' class='iconlist_icon  avia-font-fontawesome'><span class='iconlist-char ' aria-hidden='true' data-av_icon='\uf1ab' data-av_iconfont='fontawesome'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='iconlist_content_wrap'><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small   '  itemprop=\"headline\"  >Spanish | Catalan | English | French | Italian | German<\/div><\/header><div class='iconlist_content  '  itemprop=\"text\"  ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class='iconlist-timeline'><\/div><\/li>\n<\/ul><\/div><\/p>\n<\/div><\/div><div class=\"flex_cell no_margin av_one_third  avia-builder-el-16  el_after_av_cell_one_third  avia-builder-el-last   \"  style='vertical-align:middle; padding:60px; background-color:#f7f7f7; ' ><div class='flex_cell_inner' ><section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock  '   itemprop=\"text\" ><p>Carles Foz Moreno, lawyer and tax attorney since 1986.<br \/>\nHe is the CEO of his own Law Firm, Bufete Foz y Asociados, and his own Tax Consultancy, Foz Assessors.<br \/>\nHe founded FSE in 2010 and since he is FIBA Agent, Master and Doctor in Sports Law, he is the responsible for all the Legal matters surrounding the Agency.<\/p>\n<\/div><\/section>\n<\/div><\/div><\/div><div id='av-layout-grid-3'  class='av-layout-grid-container entry-content-wrapper alternate_color av-flex-cells     avia-builder-el-18  el_after_av_layout_row  avia-builder-el-last  submenu-not-first container_wrap sidebar_right' style=' '  >\n<div class=\"flex_cell no_margin av_one_third  avia-builder-el-19  el_before_av_cell_one_third  avia-builder-el-first   avia-full-stretch \"  style='background:url(https:\/\/fozsports-events.com\/wp-content\/uploads\/2025\/10\/Copia-de-10.zip-2-1030x1030.png) top left no-repeat scroll; vertical-align:middle; padding:180px 60px 180px 60px ; ' ><div class='flex_cell_inner' ><\/div><\/div><div class=\"flex_cell no_margin av_one_third  avia-builder-el-20  el_after_av_cell_one_third  el_before_av_cell_one_third   \"  style='vertical-align:middle; padding:60px; ' ><div class='flex_cell_inner' ><p><div  style='padding-bottom:10px; font-size:30px;' class='av-special-heading av-special-heading-h3  blockquote modern-quote  avia-builder-el-21  el_before_av_iconlist  avia-builder-el-first  av-inherit-size '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Miguel Servera Rodr\u00edguez<\/h3><div class ='av-subheading av-subheading_below  ' style='font-size:15px;'><p>Agent<\/p>\n<\/div><div class='special-heading-border'><div class='special-heading-inner-border' ><\/div><\/div><\/div><br \/>\n<div  class='avia-icon-list-container   avia-builder-el-22  el_after_av_heading  avia-builder-el-last '><ul class='avia-icon-list avia-icon-list-left av-iconlist-small avia_animate_when_almost_visible avia-iconlist-animate'>\n<li><div  style='color:#d63e2d; ' class='iconlist_icon  avia-font-fontawesome'><span class='iconlist-char ' aria-hidden='true' data-av_icon='\uf0ac' data-av_iconfont='fontawesome'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='iconlist_content_wrap'><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small   '  itemprop=\"headline\"  >Spain<\/div><\/header><div class='iconlist_content  '  itemprop=\"text\"  ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class='iconlist-timeline'><\/div><\/li>\n<li><div  style='color:#d63e2d; ' class='iconlist_icon  avia-font-fontawesome'><span class='iconlist-char ' aria-hidden='true' data-av_icon='\uf27e' data-av_iconfont='fontawesome'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='iconlist_content_wrap'><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small   '  itemprop=\"headline\"  >Agent<\/div><\/header><div class='iconlist_content  '  itemprop=\"text\"  ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class='iconlist-timeline'><\/div><\/li>\n<li><div  style='color:#d63e2d; ' class='iconlist_icon  avia-font-fontawesome'><span class='iconlist-char ' aria-hidden='true' data-av_icon='\uf19d' data-av_iconfont='fontawesome'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='iconlist_content_wrap'><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small   '  itemprop=\"headline\"  >Sports Director Master<\/div><\/header><div class='iconlist_content  '  itemprop=\"text\"  ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class='iconlist-timeline'><\/div><\/li>\n<li><div  style='color:#d63e2d; ' class='iconlist_icon  avia-font-fontawesome'><span class='iconlist-char ' aria-hidden='true' data-av_icon='\uf1ab' data-av_iconfont='fontawesome'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='iconlist_content_wrap'><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small   '  itemprop=\"headline\"  >Spanish | Catalan | English<\/div><\/header><div class='iconlist_content  '  itemprop=\"text\"  ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class='iconlist-timeline'><\/div><\/li>\n<\/ul><\/div><\/p>\n<\/div><\/div><div class=\"flex_cell no_margin av_one_third  avia-builder-el-23  el_after_av_cell_one_third  avia-builder-el-last   \"  style='vertical-align:middle; padding:60px; background-color:#292929; ' ><div class='flex_cell_inner' ><section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock  '   itemprop=\"text\" ><p>Miguel Servera Rodr\u00edguez is a former basketball player in all Spanish divisions, plus Germany and UK.<\/p>\n<p>He joined FSE in 2025 and he is in charge of bringing in talent and representing both professional players and young talents.<\/p>\n<\/div><\/section>\n<\/div><\/div>\n<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":30,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1471","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Team - Foz Sports Events<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fozsports-events.com\/en\/team\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Team - Foz Sports Events\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fozsports-events.com\/en\/team\/\" \/>\n<meta property=\"og:site_name\" content=\"Foz Sports Events\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-02T11:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fozsports-events.com\/en\/team\/\",\"url\":\"https:\/\/fozsports-events.com\/en\/team\/\",\"name\":\"Team - Foz Sports Events\",\"isPartOf\":{\"@id\":\"https:\/\/fozsports-events.com\/en\/#website\"},\"datePublished\":\"2017-03-02T12:52:23+00:00\",\"dateModified\":\"2025-10-02T11:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/fozsports-events.com\/en\/team\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fozsports-events.com\/en\/team\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fozsports-events.com\/en\/team\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/fozsports-events.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Team\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fozsports-events.com\/en\/#website\",\"url\":\"https:\/\/fozsports-events.com\/en\/\",\"name\":\"Foz Sports Events\",\"description\":\"Foz Sports Events\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fozsports-events.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Team - Foz Sports Events","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fozsports-events.com\/en\/team\/","og_locale":"en_US","og_type":"article","og_title":"Team - Foz Sports Events","og_url":"https:\/\/fozsports-events.com\/en\/team\/","og_site_name":"Foz Sports Events","article_modified_time":"2025-10-02T11:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fozsports-events.com\/en\/team\/","url":"https:\/\/fozsports-events.com\/en\/team\/","name":"Team - Foz Sports Events","isPartOf":{"@id":"https:\/\/fozsports-events.com\/en\/#website"},"datePublished":"2017-03-02T12:52:23+00:00","dateModified":"2025-10-02T11:03:47+00:00","breadcrumb":{"@id":"https:\/\/fozsports-events.com\/en\/team\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fozsports-events.com\/en\/team\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fozsports-events.com\/en\/team\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fozsports-events.com\/en\/"},{"@type":"ListItem","position":2,"name":"Team"}]},{"@type":"WebSite","@id":"https:\/\/fozsports-events.com\/en\/#website","url":"https:\/\/fozsports-events.com\/en\/","name":"Foz Sports Events","description":"Foz Sports Events","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fozsports-events.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/fozsports-events.com\/en\/wp-json\/wp\/v2\/pages\/1471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fozsports-events.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fozsports-events.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fozsports-events.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fozsports-events.com\/en\/wp-json\/wp\/v2\/comments?post=1471"}],"version-history":[{"count":20,"href":"https:\/\/fozsports-events.com\/en\/wp-json\/wp\/v2\/pages\/1471\/revisions"}],"predecessor-version":[{"id":12578,"href":"https:\/\/fozsports-events.com\/en\/wp-json\/wp\/v2\/pages\/1471\/revisions\/12578"}],"wp:attachment":[{"href":"https:\/\/fozsports-events.com\/en\/wp-json\/wp\/v2\/media?parent=1471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}